{"id":25749,"date":"2023-11-04T21:21:08","date_gmt":"2023-11-04T13:21:08","guid":{"rendered":"\/?page_id=25749"},"modified":"2023-11-04T22:25:11","modified_gmt":"2023-11-04T14:25:11","slug":"%e7%8e%af%e4%bf%9d%e6%b6%82%e6%96%99vocs%e6%a3%80%e9%aa%8c%e6%8a%a5%e5%91%8a","status":"publish","type":"page","link":"https:\/\/xin.nxjiasheng.com\/it\/%e7%8e%af%e4%bf%9d%e6%b6%82%e6%96%99vocs%e6%a3%80%e9%aa%8c%e6%8a%a5%e5%91%8a.html","title":{"rendered":"Rapporto di ispezione sui COV delle vernici ecologiche"},"content":{"rendered":"<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-gallery alignwide has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-style-default\"><a href=\"\/index.php\/%e6%a3%80%e9%aa%8c%e6%8a%a5%e5%91%8a\/\"><img loading=\"lazy\" decoding=\"async\" width=\"384\" height=\"245\" data-id=\"25690\" src=\"\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a1.png\" alt=\"\" class=\"wp-image-25690\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a1.png 384w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a1-300x191.png 300w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/a><figcaption class=\"wp-element-caption\">Finitura acrilica 2K all'acqua di colore bianco<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"\/index.php\/%e6%b0%b4%e6%80%a7%e9%bb%91%e8%89%b2%e9%9d%a2%e6%bc%86\/\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"307\" data-id=\"25691\" src=\"\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a2.png\" alt=\"\" class=\"wp-image-25691\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a2.png 480w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a2-300x192.png 300w\" sizes=\"auto, (max-width: 480px) 100vw, 480px\" \/><\/a><figcaption class=\"wp-element-caption\">Finitura nera all'acqua<\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-gallery alignwide has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-style-default\"><a href=\"\/index.php\/%e9%ab%98%e5%9b%ba%e4%bd%93%e4%bb%bd%e6%b8%85%e6%bc%86\/\"><img loading=\"lazy\" decoding=\"async\" width=\"478\" height=\"304\" data-id=\"25692\" src=\"\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a3.png\" alt=\"\" class=\"wp-image-25692\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a3.png 478w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a3-300x191.png 300w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/a><figcaption class=\"wp-element-caption\">Vernice ad alto solido<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"\/index.php\/%e6%b0%b4%e6%80%a7%e7%ba%a2%e8%89%b2%e9%9d%a2%e6%bc%86\/\"><img loading=\"lazy\" decoding=\"async\" width=\"475\" height=\"304\" data-id=\"25693\" src=\"\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a4.png\" alt=\"\" class=\"wp-image-25693\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a4.png 475w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u68c0\u9a8c\u62a5\u544a4-300x192.png 300w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><\/a><figcaption class=\"wp-element-caption\">Finitura rossa all'acqua<\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-gallery alignwide has-nested-images columns-default is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-style-default\"><a href=\"\/index.php\/%e6%88%90%e5%93%81%e6%bc%86%e6%b7%b1%e7%81%b0\/\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"305\" data-id=\"25705\" src=\"\/wp-content\/uploads\/2023\/11\/\u6210\u54c1\u6f06\u6df1\u7070\u68c0\u9a8c\u62a5\u544a1.png\" alt=\"\" class=\"wp-image-25705\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u6210\u54c1\u6f06\u6df1\u7070\u68c0\u9a8c\u62a5\u544a1.png 240w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u6210\u54c1\u6f06\u6df1\u7070\u68c0\u9a8c\u62a5\u544a1-236x300.png 236w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><figcaption class=\"wp-element-caption\">Vernice finita grigio scuro<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"\/index.php\/%e9%ab%98%e5%9b%ba%e4%bd%93%e4%bb%bd%e7%99%bd%e6%bc%86\/\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"306\" data-id=\"25724\" src=\"\/wp-content\/uploads\/2023\/11\/\u9ad8\u56fa\u4f53\u4efd\u767d\u6f061.png\" alt=\"\" class=\"wp-image-25724\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u9ad8\u56fa\u4f53\u4efd\u767d\u6f061.png 240w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u9ad8\u56fa\u4f53\u4efd\u767d\u6f061-235x300.png 235w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><figcaption class=\"wp-element-caption\">Vernice bianca ad alto solido<\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignwide\"><div class=\"wp-block-group__inner-container is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-gallery alignwide has-nested-images columns-default is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full is-style-default\"><a href=\"\/index.php\/%e9%ab%98%e5%88%86%e5%ad%90%e9%ab%98%e5%9b%ba%e4%bd%93%e4%bb%bd%e7%8e%af%e6%b0%a7%e5%ba%95%e6%bc%86\/\"><img loading=\"lazy\" decoding=\"async\" width=\"239\" height=\"306\" data-id=\"25730\" src=\"\/wp-content\/uploads\/2023\/11\/\u9ad8\u5206\u5b50\u9ad8\u56fa\u4f53\u4efd\u73af\u6c27\u5e95\u6f061.png\" alt=\"\" class=\"wp-image-25730\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u9ad8\u5206\u5b50\u9ad8\u56fa\u4f53\u4efd\u73af\u6c27\u5e95\u6f061.png 239w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u9ad8\u5206\u5b50\u9ad8\u56fa\u4f53\u4efd\u73af\u6c27\u5e95\u6f061-234x300.png 234w\" sizes=\"auto, (max-width: 239px) 100vw, 239px\" \/><\/a><figcaption class=\"wp-element-caption\">Primer epossidico polimerico ad alto solido<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"\/index.php\/%e9%ab%98%e5%88%86%e5%ad%90%e9%ab%98%e5%9b%ba%e4%bd%93%e4%bb%bd%e4%b8%ad%e6%b6%82%e5%ba%95%e6%bc%86\/\"><img loading=\"lazy\" decoding=\"async\" width=\"240\" height=\"304\" data-id=\"25736\" src=\"\/wp-content\/uploads\/2023\/11\/\u9ad8\u5206\u5b50\u9ad8\u56fa\u4f53\u4efd\u4e2d\u6d82\u5e95\u6f061.png\" alt=\"\" class=\"wp-image-25736\" srcset=\"https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u9ad8\u5206\u5b50\u9ad8\u56fa\u4f53\u4efd\u4e2d\u6d82\u5e95\u6f061.png 240w, https:\/\/xin.nxjiasheng.com\/wp-content\/uploads\/2023\/11\/\u9ad8\u5206\u5b50\u9ad8\u56fa\u4f53\u4efd\u4e2d\u6d82\u5e95\u6f061-237x300.png 237w\" sizes=\"auto, (max-width: 240px) 100vw, 240px\" \/><\/a><figcaption class=\"wp-element-caption\">Primer polimerico ad alto solido medio<\/figcaption><\/figure>\n<\/figure>\n<\/div><\/div>\n\n\n\n<p>\u5609\u76db\u516c\u53f8\u51fa\u54c1\u7684\u6c34\u6027\u6f06\u3001\u9ad8\u56fa\u4f53\u4efd\u6f06\u7ecf\u8fc7\u7b2c\u4e09\u65b9\u6743\u5a01\u68c0\u6d4b\u673a\u6784\u68c0\u6d4b\uff0cVOCs\u542b\u91cf\u5b8c\u5168\u8fbe\u6807\uff0c\u6280\u672f\u6c34\u5e73\u9886\u5148\u56fd\u5185\u3002<\/p>","protected":false},"excerpt":{"rendered":"<p>\u5609\u76db\u516c\u53f8\u51fa\u54c1\u7684\u6c34\u6027\u6f06\u3001\u9ad8\u56fa\u4f53\u4efd\u6f06\u7ecf\u8fc7\u7b2c\u4e09\u65b9\u6743\u5a01\u68c0\u6d4b\u673a\u6784\u68c0\u6d4b\uff0cVOCs\u542b\u91cf\u5b8c\u5168\u8fbe\u6807\uff0c\u6280\u672f\u6c34\u5e73\u9886\u5148\u56fd\u5185\u3002<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25749","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/pages\/25749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/comments?post=25749"}],"version-history":[{"count":8,"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/pages\/25749\/revisions"}],"predecessor-version":[{"id":25814,"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/pages\/25749\/revisions\/25814"}],"wp:attachment":[{"href":"https:\/\/xin.nxjiasheng.com\/it\/wp-json\/wp\/v2\/media?parent=25749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}